{"id":1083,"date":"2026-01-03T16:10:12","date_gmt":"2026-01-03T19:10:12","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=1083"},"modified":"2026-01-03T16:12:04","modified_gmt":"2026-01-03T19:12:04","slug":"trump-nao-obteve-aval-para-bombardear-venezuela-e-ataque-e-ilegal-dizem-congressistas","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/1083\/","title":{"rendered":"Trump n\u00e3o obteve aval para bombardear Venezuela e ataque \u00e9 ilegal, dizem congressistas"},"content":{"rendered":"<p class=\"texto\" style=\"text-align: justify;\">Deputados e senadores estadunidenses afirmaram que o presidente norte-americano, Donald Trump, n\u00e3o obteve autoriza\u00e7\u00e3o do Congresso para a a\u00e7\u00e3o militar na Venezuela neste s\u00e1bado, 3, o que faz o ataque ser considerado ilegal, conforme os parlamentares.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Os Estados Unidos atacaram a Venezuela com bombardeios em Caracas e em outros tr\u00eas Estados, e capturaram Nicol\u00e1s Maduro e sua esposa.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Trump confirmou a informa\u00e7\u00e3o em sua rede social, a Truth Social, e prometeu mais detalhes em coletiva de imprensa marcada para as 13h (hor\u00e1rio de Bras\u00edlia).<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">A deputada democrata Melanie Stansbury afirmou que o presidente norte-americano n\u00e3o pode realizar ataques militares sem o aval do Congresso e conclamou seus pares a impedir a continuidade das a\u00e7\u00f5es do governo dos EUA na Venezuela.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">&#8220;Sejamos claros: esses ataques s\u00e3o ilegais. O presidente n\u00e3o tem autoridade para declarar guerra nem para realizar opera\u00e7\u00f5es militares em grande escala sem o Congresso. O Congresso precisa agir para cont\u00ea-lo. Imediatamente&#8221;, disse ela, em sua conta na rede social X (ex-Twitter).<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">O deputado democrata Jim McGovern tamb\u00e9m questionou a legalidade do ataque e criticou o uso de recursos p\u00fablicos em mais uma a\u00e7\u00e3o militar, enquanto norte-americano sofrem com cortes em programas sociais.<\/p>\n<p style=\"text-align: justify;\">&#8220;Sem autoriza\u00e7\u00e3o do Congresso &#8211; e com a grande maioria dos norte-americanos contr\u00e1ria a uma a\u00e7\u00e3o militar -, Trump acabou de lan\u00e7ar um ataque injustificado e ilegal contra a Venezuela. Ele diz que n\u00e3o h\u00e1 dinheiro suficiente para a sa\u00fade dos estadunidenses &#8211; mas, de alguma forma, temos recursos ilimitados para a guerra??&#8221;, provocou.<\/p>\n<p style=\"text-align: justify;\">Fonte: <a href=\"https:\/\/www.opovo.com.br\/noticias\/mundo\/2026\/01\/03\/trump-nao-obteve-aval-para-bombardear-venezuela-e-ataque-e-ilegal-dizem-congressistas.html\" target=\"_blank\" rel=\"noopener\">O Povo<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deputados e senadores estadunidenses afirmaram que o presidente norte-americano, Donald Trump, n\u00e3o obteve autoriza\u00e7\u00e3o do Congresso para a a\u00e7\u00e3o militar na Venezuela neste s\u00e1bado, 3, o que faz o ataque&hellip;<\/p>\n","protected":false},"author":2,"featured_media":1084,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-1083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=1083"}],"version-history":[{"count":2,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1083\/revisions"}],"predecessor-version":[{"id":1086,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1083\/revisions\/1086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/1084"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=1083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=1083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=1083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}