{"id":1153,"date":"2026-01-10T08:00:25","date_gmt":"2026-01-10T11:00:25","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=1153"},"modified":"2026-01-10T04:06:02","modified_gmt":"2026-01-10T07:06:02","slug":"aplicacao-da-vacina-da-dengue-do-butantan-comecara-a-partir-do-dia-17","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/1153\/","title":{"rendered":"Aplica\u00e7\u00e3o da vacina da dengue do Butantan come\u00e7ar\u00e1 a partir do dia 17"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>O Sistema \u00danico de Sa\u00fade (SUS) vai aplicar a vacina produzida pelo Instituto Butantan, de dose \u00fanica, em tr\u00eas cidades: Maranguape (CE) e Nova Lima (MG), a partir de 17 de janeiro, e em Botucatu (SP), no dia 18.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Na luta contra a dengue, o Sistema \u00danico de Sa\u00fade (SUS) vai aplicar a vacina produzida pelo Instituto Butantan, de dose \u00fanica, em tr\u00eas cidades: Maranguape (CE) e Nova Lima (MG), a partir de 17 de janeiro, e em Botucatu (SP), no dia 18.<\/p>\n<p style=\"text-align: justify;\">A ideia \u00e9 avaliar os resultados com a imuniza\u00e7\u00e3o de pelo menos 50% dos moradores desses munic\u00edpios.<\/p>\n<p style=\"text-align: justify;\">O p\u00fablico-alvo ser\u00e1 composto pela popula\u00e7\u00e3o com a faixa et\u00e1ria entre 15 e 59 anos.<\/p>\n<p style=\"text-align: justify;\">\u201cPara essa estrat\u00e9gia, ser\u00e1 utilizada uma parte das primeiras 1,3 milh\u00e3o de doses produzidas pelo Instituto Butantan\u201d, afirmou o Minist\u00e9rio da Sa\u00fade, em nota.<\/p>\n<p style=\"text-align: justify;\"><strong>Amplia\u00e7\u00e3o<\/strong><br \/>\nO primeiro lote tamb\u00e9m ser\u00e1 destinado aos profissionais da aten\u00e7\u00e3o prim\u00e1ria, que atuam nas unidades b\u00e1sicas de sa\u00fade (UBS).<\/p>\n<p style=\"text-align: justify;\">Segundo o minist\u00e9rio, com o aumento da produ\u00e7\u00e3o de doses, a partir da parceria de transfer\u00eancia de tecnologia entre o Instituto Butantan e a empresa chinesa WuXi Vaccines, a estrat\u00e9gia ser\u00e1 gradualmente ampliada para todo o pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">A ideia \u00e9 come\u00e7ar pela popula\u00e7\u00e3o de 59 anos e avan\u00e7ar at\u00e9 o p\u00fablico de 15 anos, conforme a disponibilidade de doses.<\/p>\n<p style=\"text-align: justify;\">Atualmente, o SUS oferece a vacina em duas doses (produzida no Jap\u00e3o) para adolescentes de 10 a 14 anos.<\/p>\n<p style=\"text-align: justify;\"><strong>Efic\u00e1cia<\/strong><br \/>\nO Instituto Butantan divulgou, nesta semana, que a vacina poder\u00e1 ajudar a reduzir a quantidade de v\u00edrus em pessoas infectadas pelo pat\u00f3geno, al\u00e9m de manter efic\u00e1cia contra os diferentes gen\u00f3tipos do v\u00edrus circulantes no Brasil. A conclus\u00e3o surgiu de uma pesquisa tornada p\u00fablica pela revista The Lancet Regional Health \u2013 Americas.<\/p>\n<p style=\"text-align: justify;\">Baixas cargas virais provocam, em geral, quadros menos graves. No levantamento, os pesquisadores analisaram amostras de 365 volunt\u00e1rios que tiveram dengue sintom\u00e1tica entre 2016 e 2021 em 14 estados do Brasil.<\/p>\n<p style=\"text-align: justify;\">O estudo comparou dados dos grupos de vacinados e o de n\u00e3o vacinados.<\/p>\n<p style=\"text-align: justify;\">Segundo a pesquisa, apesar de algumas pessoas terem sido infectadas ap\u00f3s a vacina\u00e7\u00e3o, a carga viral nos vacinados foi consideravelmente menor do que em participantes n\u00e3o imunizados.<\/p>\n<p style=\"text-align: justify;\">Isso, conforme avaliaram os pesquisadores, demonstrou a efic\u00e1cia da vacina em induzir resposta imune e diminuir a replica\u00e7\u00e3o do v\u00edrus nas c\u00e9lulas.<\/p>\n<p style=\"text-align: justify;\">A vacina da dengue desenvolvida pelo Instituto Butantan foi aprovada pela Anvisa ap\u00f3s an\u00e1lise dos dados de cinco anos de acompanhamento dos 16 mil volunt\u00e1rios participantes do ensaio cl\u00ednico.<\/p>\n<p style=\"text-align: justify;\">No p\u00fablico de 12 a 59 anos, faixa et\u00e1ria indicada pela ag\u00eancia reguladora, o imunizante mostrou 74,7% de efic\u00e1cia geral e 91,6% de efic\u00e1cia contra dengue grave e com sinais de alarme.<\/p>\n<p>Fonte: <a href=\"https:\/\/www.novonoticias.com.br\/aplicacao-da-vacina-da-dengue-do-butantan-comecara-a-partir-do-dia-17\/\" target=\"_blank\" rel=\"noopener\">Novo Not\u00edcias<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Sistema \u00danico de Sa\u00fade (SUS) vai aplicar a vacina produzida pelo Instituto Butantan, de dose \u00fanica, em tr\u00eas cidades: Maranguape (CE) e Nova Lima (MG), a partir de 17&hellip;<\/p>\n","protected":false},"author":2,"featured_media":1154,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[20],"tags":[],"class_list":["post-1153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=1153"}],"version-history":[{"count":1,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1153\/revisions"}],"predecessor-version":[{"id":1155,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1153\/revisions\/1155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/1154"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=1153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=1153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=1153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}