{"id":1171,"date":"2026-01-13T12:00:35","date_gmt":"2026-01-13T15:00:35","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=1171"},"modified":"2026-01-13T00:13:27","modified_gmt":"2026-01-13T03:13:27","slug":"faculdade-se-manifesta-sobre-garoto-com-uniforme-nazista-em-formatura","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/1171\/","title":{"rendered":"Faculdade se manifesta sobre garoto com uniforme nazista em formatura"},"content":{"rendered":"<h2 class=\"Text__TextBase-sc-1d75gww-0 eOYeiH noticiaCabecalho__subtitulo\">O menino de 13 anos apareceu em fotos da formatura de medicina das irm\u00e3s com uniforme nazista. O evento foi organizado por estudantes<\/h2>\n<p>A Faculdade de Enfermagem e Medicina Nova Esperan\u00e7a (Facene) emitiu nota de repudiu \u00e0 a\u00e7\u00e3o de um adolescente que compareceu a formatura de medicina das irm\u00e3s usando um traje nazista, no \u00faltimo s\u00e1bado (10\/1), em Mossor\u00f3 (RN). Pelas redes sociais, a institui\u00e7\u00e3o classificou a manifesta\u00e7\u00e3o do jovem como <span class=\"highlight highlight-visible\">\u201crepugnante\u201d e uma \u201cafronta os valores democr\u00e1ticos, a dignidade humana e a mem\u00f3ria das v\u00edtimas do nazismo\u201d<\/span>.<\/p>\n<p>Ressaltou ainda que n\u00e3o tem qualquer participa\u00e7\u00e3o no evento de formatura da Faculdade de Medicina. \u201cO referido evento n\u00e3o contou com qualquer participa\u00e7\u00e3o, promo\u00e7\u00e3o ou financiamento da institui\u00e7\u00e3o. Ainda assim, lamentamos profundamente o ocorrido\u201d, disse. <strong>Veja nota na \u00edntegra:<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1174\" src=\"https:\/\/puxandoassunto.com.br\/site\/wp-content\/uploads\/2026\/01\/f73a9f957962cd73fce51078b5b9614f.png\" alt=\"Nota de rep\u00fadio da Facene Mossor\u00f3\" width=\"1080\" height=\"1350\" srcset=\"https:\/\/puxandoassunto.com.br\/site\/wp-content\/uploads\/2026\/01\/f73a9f957962cd73fce51078b5b9614f.png 1080w, https:\/\/puxandoassunto.com.br\/site\/wp-content\/uploads\/2026\/01\/f73a9f957962cd73fce51078b5b9614f-240x300.png 240w, https:\/\/puxandoassunto.com.br\/site\/wp-content\/uploads\/2026\/01\/f73a9f957962cd73fce51078b5b9614f-819x1024.png 819w, https:\/\/puxandoassunto.com.br\/site\/wp-content\/uploads\/2026\/01\/f73a9f957962cd73fce51078b5b9614f-768x960.png 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p>Imagens que viralizaram nas redes sociais mostram um garoto, de 13 de idade, que foi \u00e0 festa de formatura das irm\u00e3s usando um traje semelhante ao Wehrmacht (For\u00e7as Armadas unificadas da Alemanha Nazista de 1935 a 1945), durante o regime nazista de <strong>Adolf Hitler. <\/strong><span class=\"highlight highlight-visible\">Em uma das imagens, o jovem ainda faz a sauda\u00e7\u00e3o nazista.<\/span><\/p>\n<p>Segundo o cerimonial do evento, organizado pela empresa Master Produ\u00e7\u00f5es e Eventos e formandos, o adolescente era convidado das formandas e chegou ao local acompanhado dos pais, ap\u00f3s as 23h, vestindo roupas comuns. Ainda conforme a organiza\u00e7\u00e3o, ele teria trocado de roupa dentro do evento para fazer registros fotogr\u00e1ficos com a fam\u00edlia. A vestimenta passou despercebida pelos alunos e organiza\u00e7\u00e3o.<\/p>\n<p>A festa reuniu cerca de 2 mil pessoas. Integrantes da comiss\u00e3o de formatura afirmaram que s\u00f3 tomaram conhecimento do epis\u00f3dio ap\u00f3s a divulga\u00e7\u00e3o das imagens.<\/p>\n<p>Em nota publicada nas redes sociais, a presidente da comiss\u00e3o disse que os estudantes ficaram \u201cestarrecidos\u201d e que, se a situa\u00e7\u00e3o tivesse sido percebida no momento, o jovem e os respons\u00e1veis dele teriam sido retirados do local.<\/p>\n<figure id=\"attachment_4355461\" aria-describedby=\"caption-attachment-4355461\" style=\"width: 600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4355461 size-medium\" src=\"https:\/\/image.metroimg.com\/wp-content\/uploads\/92218d2d-foto-nazismo-repudio-600x400.jpg\" alt=\" Aluna que participou da formatura se manifestou ap\u00f3s epis\u00f3dio - Metr\u00f3poles\" width=\"600\" height=\"400\" data-description=\"Reprodu\u00e7\u00e3o\/Redes sociais\" data-pin=\"pinIt\" \/><figcaption id=\"caption-attachment-4355461\" class=\"wp-caption-text\">Aluna que participou da formatura se manifestou ap\u00f3s repercuss\u00e3o do epis\u00f3dio<\/figcaption><\/figure>\n<h4>Empresa se pronuncia<\/h4>\n<p>A Master Eventos repudiou o ocorrido e destacou que a apologia ao nazismo \u00e9 crime no Brasil. \u201cN\u00e3o compactuamos, n\u00e3o toleramos e n\u00e3o aceitaremos esse tipo de conduta em eventos sob nossa responsabilidade\u201d, afirmou a empresa.<\/p>\n<h4>Adolescente usa frases nazistas nas redes<\/h4>\n<p>Nas redes sociais, usu\u00e1rios apontaram que o <span class=\"highlight highlight-visible\">adolescente j\u00e1 havia publicado anteriormente fotos com s\u00edmbolos e vestimentas semelhantes, o que levantou questionamentos sobre a intencionalidade do ato<\/span>. A frase em alem\u00e3o \u201cEin Volk, ein Reich, ein F\u00fchrer\u201d, que significa \u201cUm Povo, Um Imp\u00e9rio, Um L\u00edder\u201d em alem\u00e3o, aparece na legenda de uma das redes sociais do jovem.<\/p>\n<p>A frase foi um slogan nazista central que promovia a unidade totalit\u00e1ria, a ideia de uma na\u00e7\u00e3o alem\u00e3 unificada sob um governo centralizado e a lealdade inquestion\u00e1vel a Adolf Hitler como l\u00edder supremo.<\/p>\n<p><span class=\"highlight highlight-visible\">No Brasil, a apologia ao nazismo \u00e9 crime previsto na Lei 7.716\/1989<\/span>. Como se trata de um menor de idade, o caso \u00e9 analisado como ato infracional, conforme o Estatuto da Crian\u00e7a e do Adolescente (ECA).<\/p>\n<p>Fonte: <a href=\"https:\/\/www.metropoles.com\/brasil\/faculdade-se-manifesta-sobre-garoto-com-roupa-nazista-em-formatura\" target=\"_blank\" rel=\"noopener\">Metr\u00f3poles<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O menino de 13 anos apareceu em fotos da formatura de medicina das irm\u00e3s com uniforme nazista. O evento foi organizado por estudantes A Faculdade de Enfermagem e Medicina Nova&hellip;<\/p>\n","protected":false},"author":2,"featured_media":1175,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-1171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=1171"}],"version-history":[{"count":1,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1171\/revisions"}],"predecessor-version":[{"id":1176,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1171\/revisions\/1176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/1175"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=1171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=1171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=1171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}