{"id":1184,"date":"2026-01-14T08:00:32","date_gmt":"2026-01-14T11:00:32","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=1184"},"modified":"2026-01-20T20:23:40","modified_gmt":"2026-01-20T23:23:40","slug":"dr-marcones-sa-e-liderancas-de-salgueiro-alinham-estrategias-com-joao-campos","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/1184\/","title":{"rendered":"Dr. Marcones S\u00e1 e lideran\u00e7as de Salgueiro alinham estrat\u00e9gias com Jo\u00e3o Campos"},"content":{"rendered":"<p style=\"text-align: justify;\">O ex-prefeito de Salgueiro, Dr. Marcones S\u00e1, cumpriu agenda na capital pernambucana para uma reuni\u00e3o estrat\u00e9gica com o prefeito do Recife, Jo\u00e3o Campos (PSB). O encontro, que contou tamb\u00e9m com a presen\u00e7a da vereadora Eliane Alves, marcou o in\u00edcio oficial das discuss\u00f5es sobre o futuro de Salgueiro e do Sert\u00e3o pernambucano.<\/p>\n<p style=\"text-align: justify;\">Com o lema \u201c2026 come\u00e7ou\u201d, Dr. Marcones S\u00e1 sinaliza que o seu grupo pol\u00edtico em Salgueiro est\u00e1 organizado e em plena sintonia com a lideran\u00e7a de Jo\u00e3o Campos. O objetivo central \u00e9 recolocar Salgueiro no mapa das grandes decis\u00f5es do Estado, garantindo que as demandas do Sert\u00e3o voltem a ser prioridade no Pal\u00e1cio do Campo das Princesas.<\/p>\n<p style=\"text-align: justify;\">Durante a conversa, Dr. Marcones destacou o vigor pol\u00edtico de Jo\u00e3o Campos e a import\u00e2ncia da unidade do seu grupo em Salgueiro. \u201cSaio dessa conversa animado e confiante na energia do nosso companheiro Jo\u00e3o Campos. Vamos formar a frente necess\u00e1ria para garantir que Salgueiro e regi\u00e3o voltem a estar no centro das decis\u00f5es\u201d, afirmou o ex-prefeito.<\/p>\n<p>Fonte: <a href=\"https:\/\/sertaocentral.com\/em-encontro-com-joao-campos-dr-marcones-sa-e-eliane-alves-alinham-estrategias-e-projeta-futuro-de-salgueiro-e-do-sertao\/\" target=\"_blank\" rel=\"noopener\">Sert\u00e3o Central<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ex-prefeito de Salgueiro, Dr. Marcones S\u00e1, cumpriu agenda na capital pernambucana para uma reuni\u00e3o estrat\u00e9gica com o prefeito do Recife, Jo\u00e3o Campos (PSB). O encontro, que contou tamb\u00e9m com&hellip;<\/p>\n","protected":false},"author":2,"featured_media":1185,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-1184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=1184"}],"version-history":[{"count":1,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1184\/revisions"}],"predecessor-version":[{"id":1186,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1184\/revisions\/1186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/1185"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=1184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=1184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=1184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}