{"id":1447,"date":"2026-03-27T15:31:43","date_gmt":"2026-03-27T18:31:43","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=1447"},"modified":"2026-03-27T15:31:51","modified_gmt":"2026-03-27T18:31:51","slug":"governo-de-pernambuco-atrasa-pagamento-de-jornada-extra-para-patrulha-escolar","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/1447\/","title":{"rendered":"Governo de Pernambuco atrasa pagamento de jornada extra para Patrulha Escolar"},"content":{"rendered":"<p style=\"text-align: justify;\">De <a href=\"https:\/\/blogdomagno.com.br\/governo-raquel-atrasa-pagamento-de-jornada-extra-da-pm-para-patrulha-escolar\/\" target=\"_blank\" rel=\"noopener\">Blog do Magno<\/a><\/p>\n<p style=\"text-align: justify;\">Policiais militares de Pernambuco relatam atraso no pagamento do Programa de Jornada Extra de Seguran\u00e7a (PJES) referente ao servi\u00e7o da Patrulha Escolar, com valores ainda pendentes dos meses de janeiro e fevereiro. A atividade \u00e9 realizada por agentes que atuam em seus per\u00edodos de folga, em a\u00e7\u00f5es preventivas voltadas \u00e0s escolas da rede estadual.<\/p>\n<p style=\"text-align: justify;\">De acordo com relatos da categoria, n\u00e3o h\u00e1 previs\u00e3o informada pelo governo estadual para a regulariza\u00e7\u00e3o dos pagamentos. Os profissionais apontam dificuldades para cumprir compromissos financeiros diante dos atrasos e destacam que a situa\u00e7\u00e3o j\u00e1 teria ocorrido em outras ocasi\u00f5es.<\/p>\n<h1 class=\"elementor-heading-title elementor-size-xl\" style=\"text-align: justify;\"><\/h1>\n","protected":false},"excerpt":{"rendered":"<p>De Blog do Magno Policiais militares de Pernambuco relatam atraso no pagamento do Programa de Jornada Extra de Seguran\u00e7a (PJES) referente ao servi\u00e7o da Patrulha Escolar, com valores ainda pendentes&hellip;<\/p>\n","protected":false},"author":2,"featured_media":1448,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-1447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguranca"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=1447"}],"version-history":[{"count":1,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1447\/revisions"}],"predecessor-version":[{"id":1449,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/1447\/revisions\/1449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/1448"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=1447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=1447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=1447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}