{"id":372,"date":"2025-09-30T00:11:00","date_gmt":"2025-09-30T03:11:00","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=372"},"modified":"2025-09-30T00:11:00","modified_gmt":"2025-09-30T03:11:00","slug":"foi-lancado-edital-de-acesso-a-justica-para-populacao-em-situacao-de-rua","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/372\/","title":{"rendered":"Foi lan\u00e7ado edital de acesso \u00e0 justi\u00e7a para popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua"},"content":{"rendered":"<p><em><strong>Iniciativa ir\u00e1 implementar at\u00e9 40 unidades do Cidadania PopRua em at\u00e9 21 munic\u00edpios de todas as regi\u00f5es do pa\u00eds; OSCs devem enviar propostas at\u00e9 22 de outubro<\/strong><\/em><\/p>\n<p>O Minist\u00e9rio dos Direitos Humanos e da Cidadania (MDHC), em parceria com o Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica (MJSP), lan\u00e7a, nesta segunda-feira (22), edital de chamamento para a implementa\u00e7\u00e3o de equipamento in\u00e9dito voltado ao atendimento da popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua. At\u00e9 o dia 22 de outubro, Organiza\u00e7\u00f5es da Sociedade Civil dever\u00e3o enviar propostas para implementa\u00e7\u00e3o do Cidadania PopRua nos territ\u00f3rios. Todas as informa\u00e7\u00f5es sobre a sele\u00e7\u00e3o est\u00e3o dispon\u00edveis no Edital, publicado no site do MDHC.<\/p>\n<p>O Cidadania PopRua ir\u00e1 oferecer, \u00e0 popula\u00e7\u00e3o em situa\u00e7\u00e3o de rua, servi\u00e7os que visam garantir seus direitos humanos e sua dignidade de forma integrada. Os equipamentos ir\u00e3o contar com equipes multidisciplinares que j\u00e1 t\u00eam experi\u00eancia em atender este p\u00fablico e conhecem as especificidades dos territ\u00f3rios, atuando de forma articulada \u00e0 rede de direitos humanos local. A expectativa \u00e9 de que o n\u00famero de atendimentos em servi\u00e7os possa chegar at\u00e9 60 mil por dia, considerando as 40 unidades em 21 munic\u00edpios de todas as regi\u00f5es do Brasil.<\/p>\n<p>Trata-se de um resultado da integra\u00e7\u00e3o do Programa Pontos de Apoio \u00e0 Popula\u00e7\u00e3o em Situa\u00e7\u00e3o de Rua (PAR) do MDHC e dos Centros de Acesso a Direitos e Inclus\u00e3o Social na Pol\u00edtica sobre Drogas (CAIS) do MJSP. Sua implementa\u00e7\u00e3o est\u00e1 prevista no Plano Nacional Ruas Vis\u00edveis e fortalece as a\u00e7\u00f5es do Governo do Brasil, que avan\u00e7a no cumprimento da ADPF n\u00ba 976.<\/p>\n<p>Entre os servi\u00e7os ofertados, est\u00e3o: atendimentos especializados em Direitos Humanos, recolhimento de den\u00fancias, atendimento para combate \u00e0 viol\u00eancia contra a mulher, reinser\u00e7\u00e3o escolar e profissionaliza\u00e7\u00e3o, retomada de conv\u00edvio familiar e comunit\u00e1rio e inclus\u00e3o digital. O p\u00fablico ter\u00e1 acesso a bebedouros, banheiros, guarda-volumes e m\u00e1quina de lavar.<\/p>\n<p>As Organiza\u00e7\u00f5es da Sociedade Civil (OSCs) interessadas em participar poder\u00e3o enviar propostas entre os dias 22 de setembro e 22 de outubro, exclusivamente pela plataforma Transferegov.br, e o resultado preliminar ser\u00e1 divulgado no dia 5 de novembro. Entre os crit\u00e9rios de participa\u00e7\u00e3o, est\u00e1 a comprova\u00e7\u00e3o de pelo menos tr\u00eas anos de exist\u00eancia e experi\u00eancia pr\u00e9via na realiza\u00e7\u00e3o de atividades de natureza semelhante. Cada equipamento dever\u00e1 ser or\u00e7ado em at\u00e9 R$1,5 milh\u00f5es.<\/p>\n<p><a href=\"https:\/\/www.gov.br\/mdh\/pt-br\/navegue-por-temas\/populacao-em-situacao-de-rua\/publicacoes\/editais\" target=\"_blank\" rel=\"noopener\">Confira o edital na \u00edntegra<\/a><\/p>\n<p><a href=\"https:\/\/www.gov.br\/mdh\/pt-br\/assuntos\/noticias\/2025\/setembro\/mdhc-e-mjsp-lancam-edital-de-equipamento-que-inaugura-rede-de-atendimento-de-direitos-humanos-e-acesso-a-justica-para-populacao-em-situacao-de-rua\" target=\"_blank\" rel=\"noopener\">Confira esta not\u00edcia na \u00edntegra<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iniciativa ir\u00e1 implementar at\u00e9 40 unidades do Cidadania PopRua em at\u00e9 21 munic\u00edpios de todas as regi\u00f5es do pa\u00eds; OSCs devem enviar propostas at\u00e9 22 de outubro O Minist\u00e9rio dos&hellip;<\/p>\n","protected":false},"author":2,"featured_media":373,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[42],"tags":[],"class_list":["post-372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-direitos-humanos"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=372"}],"version-history":[{"count":1,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/372\/revisions"}],"predecessor-version":[{"id":374,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/372\/revisions\/374"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/373"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}