{"id":533,"date":"2025-10-20T12:00:27","date_gmt":"2025-10-20T15:00:27","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=533"},"modified":"2025-10-19T14:29:56","modified_gmt":"2025-10-19T17:29:56","slug":"professores-contratados-terao-direito-ao-mesmo-salario-dos-concursados","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/533\/","title":{"rendered":"Professores contratados ter\u00e3o direito ao mesmo sal\u00e1rio dos concursados"},"content":{"rendered":"<p><span class=\"x1lliihq x1plvlek xryxfnj x1n2onr6 xyejjpt x15dsfln x193iq5w xeuugli x1fj9vlw x13faqbe x1vvkbs x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x x1i0vuye xvs91rp xo1l8bm x5n08af x10wh9bi xpm28yp x8viiok x1o7cslx\" dir=\"auto\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs xt0psk2 x1i0vuye xvs91rp xo1l8bm x5n08af x10wh9bi xpm28yp x8viiok x1o7cslx x126k92a\">A C\u00e2mara dos Deputados aprovou projeto de lei, nesta ter\u00e7a-feira, 14, que garante o piso salarial de profissionais do magist\u00e9rio p\u00fablico da educa\u00e7\u00e3o b\u00e1sica aos professores contratados por tempo determinado. A proposta ser\u00e1 enviada ao Senado.<\/p>\n<p>De autoria do deputado Rafael Brito (MDB-AL), o Projeto de Lei 672\/25 foi aprovado na forma do substitutivo da deputada Carol Dartora (PT-PR), relatora de Plen\u00e1rio. O piso salarial do magist\u00e9rio \u00e9 de R$ 4.867,77.<\/p>\n<p>Com a reda\u00e7\u00e3o proposta, o piso ser\u00e1 aplic\u00e1vel aos profissionais do magist\u00e9rio p\u00fablico da educa\u00e7\u00e3o b\u00e1sica contratados por tempo determinado e com a forma\u00e7\u00e3o m\u00ednima determinada pela Lei de Diretrizes e Bases da Educa\u00e7\u00e3o Nacional (LDB).<\/span><\/span><\/p>\n<p>Segundo a lei modificada, que garante o piso, ele vale inclusive para os que exer\u00e7am atividades de suporte pedag\u00f3gico \u00e0 doc\u00eancia, como dire\u00e7\u00e3o ou administra\u00e7\u00e3o, planejamento, inspe\u00e7\u00e3o, supervis\u00e3o, orienta\u00e7\u00e3o e coordena\u00e7\u00e3o educacionais.<\/p>\n<p>Carol Dartora afirma que a maioria dos estados j\u00e1 paga o piso a professores tempor\u00e1rios, usando o <span id=\"4274\" class=\"termoGlossario\" title=\"\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\" data-original-title=\"O Fundo de Manuten\u00e7\u00e3o e Desenvolvimento da Educa\u00e7\u00e3o B\u00e1sica e de Valoriza\u00e7\u00e3o dos Profissionais da Educa\u00e7\u00e3o (Fundeb) \u00e9 formado por recursos estaduais, municipais e federais e destina-se a promover a educa\u00e7\u00e3o infantil, o ensino fundamental e m\u00e9dio, inclusive a educa\u00e7\u00e3o de jovens e adultos. Os recursos do Fundeb s\u00e3o distribu\u00eddos de acordo com o n\u00famero de alunos da educa\u00e7\u00e3o b\u00e1sica, com base em dados do censo escolar do ano anterior. Pelo menos 60% dos recursos do fundo s\u00e3o usados no pagamento dos sal\u00e1rios dos professores.\">Fundeb<\/span> como principal fonte de custeio dessa despesa. &#8220;O projeto n\u00e3o implica em cria\u00e7\u00e3o de nova despesa ou transfer\u00eancia indevida de encargos aos entes federativos&#8221;, declarou.<\/p>\n<p><strong>Tema na Justi\u00e7a<\/strong><br \/>\nO Supremo Tribunal Federal (STF) tamb\u00e9m analisa a aplicabilidade do piso salarial para profissionais do magist\u00e9rio tempor\u00e1rios por meio do julgamento de um recurso extraordin\u00e1rio do governo de Pernambuco contra decis\u00e3o do Tribunal de Justi\u00e7a daquele estado que concedia a uma professora o direito a receber o piso.<\/p>\n<p>O recurso ser\u00e1 julgado com <span id=\"4420\" class=\"termoGlossario\" title=\"\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\" data-original-title=\"Instrumento com previs\u00e3o constitucional que autoriza o Supremo Tribunal Federal (STF) a selecionar os recursos extraordin\u00e1rios que ir\u00e1 analisar de acordo com crit\u00e9rios de relev\u00e2ncia jur\u00eddica, pol\u00edtica, social ou econ\u00f4mica. Uma vez constatada a exist\u00eancia de repercuss\u00e3o geral, o STF analisa o m\u00e9rito da quest\u00e3o e a decis\u00e3o \u00e9 aplicada depois pelas inst\u00e2ncias inferiores, em casos id\u00eanticos. Isso reduz o n\u00famero de processos encaminhados ao Supremo.\">repercuss\u00e3o geral<\/span>, ou seja, por haver grande n\u00famero de processos da mesma natureza, a decis\u00e3o ser\u00e1 aplicada a todos os casos.<\/p>\n<p><strong>Corre\u00e7\u00e3o<\/strong><br \/>\nA relatora, deputada Carol Dartora, afirmou que a proposta corrige uma lacuna na lei do Piso Nacional do Magist\u00e9rio. &#8220;Em muitos casos, os professores est\u00e3o sendo contratados de forma tempor\u00e1ria, mas atuam por per\u00edodo prolongado&#8221;, disse ela, ao citar que 43,6% dos docentes tempor\u00e1rios atuam h\u00e1 pelo menos 11 anos como professor. &#8220;Ningu\u00e9m se forma para ser professor tempor\u00e1rio, mas pra ser professor&#8221;, ressaltou.<\/p>\n<p>Segundo a relatora, isso ocorre porque \u00e9 mais barato para as redes contratar tempor\u00e1rios. Atualmente, h\u00e1 51,6% de professores tempor\u00e1rios e 46,5% de efetivos nas redes de ensino.<\/p>\n<p>Carol Dartora afirmou que, como professora tempor\u00e1ria, foi impedida de participar do cotidiano da escola. &#8220;Muitas vezes, o professor n\u00e3o tem condi\u00e7\u00f5es de desenvolver v\u00ednculos na escola, com os estudantes. Quando n\u00e3o h\u00e1 v\u00ednculo, n\u00e3o h\u00e1 aprendizado&#8221;, disse, ao criticar a precariza\u00e7\u00e3o dessa atividade.<\/p>\n<p>O l\u00edder do governo, deputado Jos\u00e9 Guimar\u00e3es (PT-CE), disse que participou de reuni\u00f5es com ministros de diferentes pastas para viabilizar a proposta. \u201cO governo vai encaminhar o voto favor\u00e1vel como forma de homenagear os professores\u201d, declarou.<\/p>\n<p><strong>Debate em Plen\u00e1rio<\/strong><br \/>\nO deputado Tarc\u00edsio Motta (Psol-RJ) afirmou que governos usam a ideia de professor tempor\u00e1rio para economizar recursos \u00e0s custas da qualidade da educa\u00e7\u00e3o. &#8220;Como ele recebe menos, tem de dar aula em v\u00e1rios lugares, n\u00e3o consegue dar aten\u00e7\u00e3o necess\u00e1ria para aquelas crian\u00e7as, jovens e adultos. Os estudantes sofrem, e o governo economiza dinheiro&#8221;, criticou.<\/p>\n<p>Por\u00e9m, o deputado Luiz Lima (Novo-RJ) avaliou que \u00e9 imposs\u00edvel, de uma hora para outra, igualar os sal\u00e1rios de professores tempor\u00e1rios e concursados. &#8220;Isso \u00e9 uma ideia fict\u00edcia, rom\u00e2ntica e impratic\u00e1vel. Os munic\u00edpios mais pobres v\u00e3o entrar na Justi\u00e7a e v\u00e3o ganhar&#8221;, afirmou.<\/p>\n<p>Para o deputado Cabo Gilberto Silva (PL-PB), ainda falta resolver o pagamento do piso nacional dos professores efetivos, antes de estabelecer a mesma medida para os tempor\u00e1rios.<\/p>\n<p>Fonte: <a href=\"https:\/\/www.camara.leg.br\/noticias\/1211712-camara-aprova-pagamento-de-piso-salarial-dos-professores-para-contratos-temporarios\/\" target=\"_blank\" rel=\"noopener\">Ag\u00eancia C\u00e2mara de Not\u00edcias<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara dos Deputados aprovou projeto de lei, nesta ter\u00e7a-feira, 14, que garante o piso salarial de profissionais do magist\u00e9rio p\u00fablico da educa\u00e7\u00e3o b\u00e1sica aos professores contratados por tempo determinado.&hellip;<\/p>\n","protected":false},"author":2,"featured_media":534,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trabalho"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=533"}],"version-history":[{"count":1,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/533\/revisions"}],"predecessor-version":[{"id":535,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/533\/revisions\/535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/534"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}