{"id":599,"date":"2025-10-27T15:00:41","date_gmt":"2025-10-27T18:00:41","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=599"},"modified":"2025-10-27T00:34:11","modified_gmt":"2025-10-27T03:34:11","slug":"ibge-anuncia-processo-seletivo-com-mais-de-9-mil-vagas","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/599\/","title":{"rendered":"IBGE anuncia processo seletivo com mais de 9 mil vagas"},"content":{"rendered":"<p><span class=\"x1lliihq x1plvlek xryxfnj x1n2onr6 xyejjpt x15dsfln x193iq5w xeuugli x1fj9vlw x13faqbe x1vvkbs x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x x1i0vuye xvs91rp xo1l8bm x5n08af x10wh9bi xpm28yp x8viiok x1o7cslx\" dir=\"auto\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs xt0psk2 x1i0vuye xvs91rp xo1l8bm x5n08af x10wh9bi xpm28yp x8viiok x1o7cslx x126k92a\">O Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) anunciou o lan\u00e7amento de um Processo Seletivo Simplificado com 9.580 vagas tempor\u00e1rias para refor\u00e7ar a capacidade operacional na institui\u00e7\u00e3o. A Funda\u00e7\u00e3o Get\u00falio Vargas (FGV) foi oficialmente contratada como banca organizadora.<\/span><\/span><\/p>\n<p>\u201cO PSS para tempor\u00e1rios \u00e9 fundamental para o funcionamento das pesquisas estat\u00edsticas e geogr\u00e1ficas do pa\u00eds. Ele permite a contrata\u00e7\u00e3o de profissionais que atuam na coleta de dados atualizados e de alcance nacional\u201d, disse o presidente do IBGE, Marcio Pochmann.<\/p>\n<p>\u201cPara os participantes, representa uma oportunidade de qualifica\u00e7\u00e3o profissional e experi\u00eancia t\u00e9cnica. Em s\u00edntese, o processo refor\u00e7a o papel do IBGE como institui\u00e7\u00e3o estrat\u00e9gica para o desenvolvimento nacional, ampliando sua capacidade operacional e fortalecendo o Sistema Estat\u00edstico e Geogr\u00e1fico Brasileiro\u201d, completou.<\/p>\n<p>O pr\u00f3ximo processo seletivo simplificado ofertar\u00e1 8.480 vagas para a fun\u00e7\u00e3o de Agente de Pesquisas e Mapeamento (APM) e 1.100 vagas para a fun\u00e7\u00e3o de Supervisor de Coleta e Qualidade (SCQ). J\u00e1 a publica\u00e7\u00e3o dos editais est\u00e1 prevista para novembro de 2025, com provas em janeiro de 2026 e divulga\u00e7\u00e3o do resultado final em mar\u00e7o do mesmo ano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) anunciou o lan\u00e7amento de um Processo Seletivo Simplificado com 9.580 vagas tempor\u00e1rias para refor\u00e7ar a capacidade operacional na institui\u00e7\u00e3o. A Funda\u00e7\u00e3o Get\u00falio&hellip;<\/p>\n","protected":false},"author":2,"featured_media":600,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concurso-publico"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=599"}],"version-history":[{"count":2,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/599\/revisions"}],"predecessor-version":[{"id":603,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/599\/revisions\/603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/600"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}