{"id":665,"date":"2025-11-04T08:00:51","date_gmt":"2025-11-04T11:00:51","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=665"},"modified":"2025-11-04T12:51:03","modified_gmt":"2025-11-04T15:51:03","slug":"xicao-tavares-deve-anunciar-rompimento-com-wilson-pizza-e-joao-de-santinha","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/665\/","title":{"rendered":"Xic\u00e3o Tavares deve anunciar rompimento com Wilson Pizza e Jo\u00e3o de Santinha"},"content":{"rendered":"<p><span class=\"x1lliihq x1plvlek xryxfnj x1n2onr6 xyejjpt x15dsfln x193iq5w xeuugli x1fj9vlw x13faqbe x1vvkbs x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x x1i0vuye xvs91rp xo1l8bm x5n08af x10wh9bi xpm28yp x8viiok x1o7cslx\" dir=\"auto\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs xt0psk2 x1i0vuye xvs91rp xo1l8bm x5n08af x10wh9bi xpm28yp x8viiok x1o7cslx x126k92a\">O clima pol\u00edtico em Verdejante promete esquentar nos pr\u00f3ximos dias. O prefeito Xic\u00e3o Tavares deve anunciar oficialmente, ainda esta semana, o rompimento pol\u00edtico com os irm\u00e3os Wilson Pizzas e Jo\u00e3o de Santinha, ex-vice-prefeito e vereador, respectivamente.<\/span><\/span><\/p>\n<p>De acordo com informa\u00e7\u00f5es de bastidores, o principal motivo para o afastamento seria a alian\u00e7a dos irm\u00e3os com o deputado federal Augusto Coutinho, parlamentar que, segundo fontes pr\u00f3ximas ao gestor, prometeu muito \u00e0 cidade, mas entregou pouco em termos de a\u00e7\u00f5es e investimentos concretos.<\/p>\n<p>A decis\u00e3o de Xic\u00e3o refor\u00e7a seu posicionamento firme dentro da gest\u00e3o municipal. O prefeito tem mostrado que infidelidade pol\u00edtica n\u00e3o tem espa\u00e7o em seu governo.<br \/>\nSitua\u00e7\u00e3o semelhante j\u00e1 havia ocorrido meses atr\u00e1s, quando ele rompeu politicamente com os vereadores Edil\u00e2nio Carvalho e Felipe do Angico, tamb\u00e9m por diverg\u00eancias e falta de alinhamento com o grupo de situa\u00e7\u00e3o.<\/p>\n<p>Nos pr\u00f3ximos dias, a expectativa \u00e9 de que o prefeito torne p\u00fablica sua decis\u00e3o, oficializando o rompimento e reposicionando seu grupo pol\u00edtico.<\/p>\n<p>Fonte e arte: <a href=\"https:\/\/sertaocentral.com\/xicao-tavares-deve-anunciar-rompimento-politico-com-irmaos-wilson-pizzas-e-joao-de-santinha\/\" target=\"_blank\" rel=\"noopener\">Sert\u00e3o Central<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O clima pol\u00edtico em Verdejante promete esquentar nos pr\u00f3ximos dias. O prefeito Xic\u00e3o Tavares deve anunciar oficialmente, ainda esta semana, o rompimento pol\u00edtico com os irm\u00e3os Wilson Pizzas e Jo\u00e3o&hellip;<\/p>\n","protected":false},"author":2,"featured_media":666,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=665"}],"version-history":[{"count":2,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/665\/revisions"}],"predecessor-version":[{"id":668,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/665\/revisions\/668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/666"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}