{"id":736,"date":"2025-11-13T12:00:46","date_gmt":"2025-11-13T15:00:46","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=736"},"modified":"2025-11-12T21:52:42","modified_gmt":"2025-11-13T00:52:42","slug":"ministerio-publico-de-verdejante-apressa-camara-de-vereadores-para-exonerar-comissionados","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/736\/","title":{"rendered":"Minist\u00e9rio Publico de Verdejante apressa C\u00e2mara de Vereadores para exonerar comissionados"},"content":{"rendered":"<p><span class=\"x1lliihq x1plvlek xryxfnj x1n2onr6 xyejjpt x15dsfln x193iq5w xeuugli x1fj9vlw x13faqbe x1vvkbs x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x x1i0vuye xvs91rp xo1l8bm x5n08af x10wh9bi xpm28yp x8viiok x1o7cslx\" dir=\"auto\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs xt0psk2 x1i0vuye xvs91rp xo1l8bm x5n08af x10wh9bi xpm28yp x8viiok x1o7cslx x126k92a\">O Minist\u00e9rio P\u00fablico de Pernambuco (MPPE), por meio da Promotoria de Justi\u00e7a de Verdejante, emitiu uma recomenda\u00e7\u00e3o formal ao presidente da C\u00e2mara Municipal de Verdejante, solicitando uma s\u00e9rie de medidas relacionadas \u00e0 estrutura administrativa e \u00e0 legalidade dos cargos p\u00fablicos da Casa Legislativa.<\/span><\/span><\/p>\n<p>No documento, datado de 31 de outubro de 2025 e assinado pelo promotor de Justi\u00e7a Leon Klinsman Farias Ferreira, o MPPE determina que a C\u00e2mara envie, no prazo de 10 dias, c\u00f3pia da minuta da Resolu\u00e7\u00e3o que est\u00e1 sendo elaborada para estruturar os cargos efetivos do Legislativo.<\/p>\n<p>Al\u00e9m disso, o Minist\u00e9rio P\u00fablico recomenda que o presidente promova, com m\u00e1xima urg\u00eancia e no prazo m\u00e1ximo de 30 dias, a cria\u00e7\u00e3o legal e formal do cargo de Analista Legislativo (Controle Interno), bem como dos demais cargos ofertados no Edital n\u00ba 001\/2024, com o objetivo de sanar a ilegalidade j\u00e1 reconhecida pela pr\u00f3pria C\u00e2mara.<\/p>\n<p>Ap\u00f3s a aprova\u00e7\u00e3o da norma, o \u00f3rg\u00e3o ministerial orienta que seja feita a imediata nomea\u00e7\u00e3o de Antonio Aidilton Alves Rodrigues Junior, aprovado em 1\u00ba lugar para o referido cargo.<\/p>\n<p>O MPPE tamb\u00e9m solicita a exonera\u00e7\u00e3o do servidor comissionado atualmente ocupante da fun\u00e7\u00e3o de Controlador Interno, ressaltando que, por se tratar de uma fun\u00e7\u00e3o de natureza t\u00e9cnica e permanente, ela deve ser exercida por servidor efetivo concursado, conforme entendimento firmado pelo Supremo Tribunal Federal (RE n\u00ba 1.264.676-SC).<\/p>\n<p>Por fim, o promotor Leon Klinsman destacou que o n\u00e3o cumprimento da recomenda\u00e7\u00e3o poder\u00e1 levar \u00e0 ado\u00e7\u00e3o de medidas legais cab\u00edveis para garantir a implementa\u00e7\u00e3o das determina\u00e7\u00f5es ministeriais.<\/p>\n<p>A recomenda\u00e7\u00e3o refor\u00e7a o compromisso do Minist\u00e9rio P\u00fablico com a legalidade, a transpar\u00eancia e o respeito \u00e0s normas constitucionais no servi\u00e7o p\u00fablico, especialmente no que se refere \u00e0 ocupa\u00e7\u00e3o de cargos t\u00e9cnicos e permanentes por servidores efetivos.<\/p>\n<p>Fonte: <a href=\"https:\/\/sertaocentral.com\/ministerio-publico-da-prazo-para-camara-de-verdejante-demitir-comissionado-e-nomear-concursado\/\" target=\"_blank\" rel=\"noopener\">Sert\u00e3o Central<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico de Pernambuco (MPPE), por meio da Promotoria de Justi\u00e7a de Verdejante, emitiu uma recomenda\u00e7\u00e3o formal ao presidente da C\u00e2mara Municipal de Verdejante, solicitando uma s\u00e9rie de medidas&hellip;<\/p>\n","protected":false},"author":2,"featured_media":737,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concurso-publico"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=736"}],"version-history":[{"count":2,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/736\/revisions"}],"predecessor-version":[{"id":739,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/736\/revisions\/739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/737"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}