{"id":776,"date":"2025-11-19T08:00:26","date_gmt":"2025-11-19T11:00:26","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=776"},"modified":"2025-11-19T00:11:28","modified_gmt":"2025-11-19T03:11:28","slug":"incendio-de-grandes-proporcoes-atinge-galpao-com-pneus-em-macaiba","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/776\/","title":{"rendered":"Inc\u00eandio de grandes propor\u00e7\u00f5es atinge galp\u00e3o com pneus em Maca\u00edba"},"content":{"rendered":"<p>Um inc\u00eandio de grandes propor\u00e7\u00f5es que come\u00e7ou o fim da manh\u00e3 desta ter\u00e7a-feira (18) atingiu uma \u00e1rea de mata e um galp\u00e3o em Maca\u00edba, na Grande Natal. At\u00e9 \u00e0s 14h20, os bombeiros permaneciam no combate \u00e0s chamas.<\/p>\n<p>Segundo o Corpo de Bombeiros, o fogo atingiu um galp\u00e3o que armazena pneus e estava em \u00e1reas de mata ao redor do im\u00f3vel. A corpora\u00e7\u00e3o informou que n\u00e3o havia feridos.<\/p>\n<p>As chamas atingiram inclusive uma \u00e1rea pr\u00f3xima \u00e0 Unidade de Pronto-Atendimento (UPA) de Maca\u00edba, na comunidade Jundia\u00ed.<\/p>\n<p>O Corpo de Bombeiros informou que atua com quatro equipes de combate a inc\u00eandio no local, concentrando esfor\u00e7os na prote\u00e7\u00e3o da UPA.<\/p>\n<p>A fuma\u00e7a densa e escura foi vista de v\u00e1rias regi\u00f5es da regi\u00e3o metropolitana de Natal.<\/p>\n<p>O Corpo de Bombeiros informou que, segundo populares, moradores teriam colocado fogo em uma \u00e1rea de vegeta\u00e7\u00e3o pr\u00f3xima e, devido ao vento, as chamas se descontrolaram e alcan\u00e7aram o galp\u00e3o.<\/p>\n<p>Um caminh\u00e3o de combate a inc\u00eandios do Corpo de Bombeiros estava no local, at\u00e9 a \u00faltima atualiza\u00e7\u00e3o desta reportagem, e contava com apoio de caminh\u00f5es-pipa da Defesa Civil.<\/p>\n<p>A equipe informou \u00e0 Inter TV Cabugi que solicitou apoio de mais militares no local.<\/p>\n<p>Em nota, a prefeitura do munic\u00edpio informou que o fogo come\u00e7ou na vegeta\u00e7\u00e3o \u00e0s margens da RN 160 e se alastrou at\u00e9 o galp\u00e3o onde s\u00e3o acondicionados os pneus recolhidos pela Secretaria Municipal de Meio Ambiente e Urbanismo para a destina\u00e7\u00e3o final adequada.<\/p>\n<p>Fonte: G1\/RN\/Foto: Vin\u00edcius Marinho\/Inter TV Cabugi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um inc\u00eandio de grandes propor\u00e7\u00f5es que come\u00e7ou o fim da manh\u00e3 desta ter\u00e7a-feira (18) atingiu uma \u00e1rea de mata e um galp\u00e3o em Maca\u00edba, na Grande Natal. At\u00e9 \u00e0s 14h20,&hellip;<\/p>\n","protected":false},"author":2,"featured_media":777,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=776"}],"version-history":[{"count":1,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/776\/revisions"}],"predecessor-version":[{"id":778,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/776\/revisions\/778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/777"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}