{"id":860,"date":"2025-12-03T20:05:38","date_gmt":"2025-12-03T23:05:38","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=860"},"modified":"2025-12-08T01:00:11","modified_gmt":"2025-12-08T04:00:11","slug":"com-nova-regulamentacao-cursos-e-titulos-garantem-ganhos-salariais-a-servidores-do-estado","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/860\/","title":{"rendered":"Com nova regulamenta\u00e7\u00e3o, cursos e t\u00edtulos garantem ganhos salariais a servidores do Estado de Pernambuco"},"content":{"rendered":"<p style=\"text-align: justify;\"><span class=\"x1lliihq x1plvlek xryxfnj x1n2onr6 xyejjpt x15dsfln x193iq5w xeuugli x1fj9vlw x13faqbe x1vvkbs x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x x1i0vuye xvs91rp xo1l8bm x5n08af x10wh9bi xpm28yp x8viiok x1o7cslx\" dir=\"auto\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs xt0psk2 x1i0vuye xvs91rp xo1l8bm x5n08af x10wh9bi xpm28yp x8viiok x1o7cslx x126k92a\">O Governo de Pernambuco regulamentou, por meio do decreto N\u00ba 59.890, publicado no Di\u00e1rio Oficial desta ter\u00e7a-feira (2), a progress\u00e3o por eleva\u00e7\u00e3o de n\u00edvel de qualifica\u00e7\u00e3o ou titula\u00e7\u00e3o profissional de servidores de \u00f3rg\u00e3os e entidades da administra\u00e7\u00e3o direta, de autarquia e fundacional do Poder Executivo Estadual.<\/span><\/span><\/p>\n<p>Segundo o decreto, est\u00e3o inclusos nesta regulamenta\u00e7\u00e3o os servidores que tiverem capacita\u00e7\u00e3o ou curso espec\u00edfico voltado ao aprimoramento das atribui\u00e7\u00f5es do cargo ocupado, al\u00e9m de titula\u00e7\u00e3o de cursos de especializa\u00e7\u00e3o, mestrado, doutorado ou p\u00f3s-doutorado.<\/p>\n<p>Outro caso em que se encaixa na progress\u00e3o por eleva\u00e7\u00e3o de n\u00edvel de qualifica\u00e7\u00e3o ou titula\u00e7\u00e3o profissional \u00e9 quando h\u00e1 mudan\u00e7a de matriz, respeitada a classe e faixa anteriormente ocupadas.<\/p>\n<p>Est\u00e3o sujeitos a essa nova regulamenta\u00e7\u00e3o os servidores que ocupam cargos em Grupos Ocupacionais de Meio Ambiente e Sustentabilidade (GOMAS); Defesa e Fiscaliza\u00e7\u00e3o Agropecu\u00e1ria (GODFA); Recursos H\u00eddricos e Clim\u00e1ticos (GORHC); Policial Civil (GOPC); Gest\u00e3o T\u00e9cnico Administrativa (GOGTA); Fiscaliza\u00e7\u00e3o Sanit\u00e1ria da Sa\u00fade (GOFSS); Sa\u00fade P\u00fablica (GOSP); Hematologia e Hemoterapia (GOHH); Magist\u00e9rio Superior (GOMS) e T\u00e9cnicos em Gest\u00e3o Universit\u00e1ria.<\/p>\n<p>Tamb\u00e9m est\u00e3o inclu\u00eddos nesta nova regulamenta\u00e7\u00e3o m\u00e9dicos, servidores do Quadro Pr\u00f3prio da Procuradoria Geral do Estado e do Quadro da Secretaria de Educa\u00e7\u00e3o.<\/p>\n<p>A legisla\u00e7\u00e3o tamb\u00e9m prev\u00ea que ser\u00e1 aceito curso de qualifica\u00e7\u00e3o ou titula\u00e7\u00e3o profissional que n\u00e3o se enquadre inicialmente nas \u00e1reas definidas previamente pelos \u00f3rg\u00e3os e entidades, mas que correspondam \u00e0s compet\u00eancias institucionais onde est\u00e1 lotado o servidor, ou ainda relacionadas \u00e0 necessidade do servi\u00e7o, desde que autorizadas pelo seu dirigente m\u00e1ximo.<\/p>\n<p>Vale destacar que este decreto poder\u00e1 ser extensivo a outros Planos de Cargos, Carreiras e Vencimentos dos cargos dos Quadros de Pessoal, desde que autorizado e exista previs\u00e3o legal espec\u00edfica para sua aplica\u00e7\u00e3o.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">No entanto, as progress\u00f5es por eleva\u00e7\u00e3o de n\u00edvel de qualifica\u00e7\u00e3o ou titula\u00e7\u00e3o profissional que j\u00e1 possuem regulamenta\u00e7\u00e3o espec\u00edfica n\u00e3o seguiram as diretrizes deste novo decreto.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\"><strong>Comprova\u00e7\u00e3o da titula\u00e7\u00e3o<\/strong><\/p>\n<p class=\"texto\" style=\"text-align: justify;\">A comprova\u00e7\u00e3o da titula\u00e7\u00e3o dos servidores, por meio da conclus\u00e3o de curso de p\u00f3s-gradua\u00e7\u00e3o stricto sensu (mestrado, doutorado e p\u00f3s-doutorado) e lato sensu (cursos de especializa\u00e7\u00e3o) deve obedecer aos seguintes crit\u00e9rios gerais:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Os cursos devem ser realizados em institui\u00e7\u00f5es de ensino superior credenciadas e reconhecidas pelo Minist\u00e9rio da Educa\u00e7\u00e3o &#8211; MEC.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Os cursos, quando ministrados por institui\u00e7\u00f5es de ensino superior no exterior, devem ser reconhecidos e validados por institui\u00e7\u00e3o brasileira competente.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Cada curso de p\u00f3s-gradua\u00e7\u00e3o stricto sensu ou lato sensu realizado somente ser\u00e1 considerado para uma \u00fanica progress\u00e3o, exceto nos casos de acumula\u00e7\u00e3o legal de cargos.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Os diplomas ou certificados utilizados como requisito de ingresso no concurso p\u00fablico n\u00e3o poder\u00e3o ser reapresentados para a progress\u00e3o por eleva\u00e7\u00e3o de n\u00edvel de qualifica\u00e7\u00e3o ou titula\u00e7\u00e3o profissional.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Para a valida\u00e7\u00e3o, devem ser considerados cursos nas modalidades presencial, semipresencial ou \u00e0 dist\u00e2ncia, conclu\u00eddos a qualquer tempo, oferecidos por institui\u00e7\u00f5es de ensino reconhecidas pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC).<\/li>\n<\/ul>\n<p class=\"texto\" style=\"text-align: justify;\"><strong>Comprova\u00e7\u00e3o de de cursos de qualifica\u00e7\u00e3o profissional<\/strong><\/p>\n<p class=\"texto\" style=\"text-align: justify;\">J\u00e1 os cursos de qualifica\u00e7\u00e3o profissional devem seguir os seguintes alguns crit\u00e9rio gerais para serem validados como:<\/p>\n<ul style=\"text-align: justify;\">\n<li>As capacita\u00e7\u00f5es ou cursos devem ter carga hor\u00e1ria m\u00ednima de 8 (oito) horas.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Quando os cursos forem realizados na modalidade on-line, o limite de carga hor\u00e1ria mensal ser\u00e1 de 80 (oitenta) horas.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Ser\u00e3o\u00a0aceito certificado de cursos quando ministrados por institui\u00e7\u00f5es de ensino, pelos \u00f3rg\u00e3os destinados \u00e0 capacita\u00e7\u00e3o dos servidores do Estado ou outros entes federativos, por entidades parceiras e entidades privadas.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Os cursos quando ministrados por institui\u00e7\u00f5es de ensino superior no exterior devem ser reconhecidos e validados por institui\u00e7\u00e3o brasileira competente.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Para a valida\u00e7\u00e3o, devem ser considerados os cursos nas modalidades presencial, semipresencial ou \u00e0 dist\u00e2ncia, conclu\u00eddos a qualquer tempo.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Os cursos realizados on-line, com inscri\u00e7\u00f5es em per\u00edodos concomitantes, devem observar o contido no inciso II, sob pena de deixarem de ser considerados para fins de progress\u00e3o.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Cada curso realizado somente ser\u00e1 considerado para uma \u00fanica progress\u00e3o, exceto nos casos de acumula\u00e7\u00e3o legal de cargos.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>S\u00f3 poder\u00e1 ser utilizada para progress\u00e3o por qualifica\u00e7\u00e3o, carga hor\u00e1ria de certificados de gradua\u00e7\u00e3o\/t\u00edtulos, caso exista previs\u00e3o na legisla\u00e7\u00e3o da categoria\/cargo do servidor.<\/li>\n<\/ul>\n<p class=\"texto\" style=\"text-align: justify;\"><strong>Progress\u00e3o de servidores est\u00e1veis<\/strong><\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Com rela\u00e7\u00e3o \u00e0 progress\u00e3o por eleva\u00e7\u00e3o do n\u00edvel de qualifica\u00e7\u00e3o ou titula\u00e7\u00e3o profissional de servidor est\u00e1vel, o funcion\u00e1rio dever\u00e1 apresentar requerimento, a qualquer tempo, ap\u00f3s a conclus\u00e3o do est\u00e1gio probat\u00f3rio, \u00e0 \u00e1rea de gest\u00e3o de pessoas do seu \u00f3rg\u00e3o de origem, anexando a documenta\u00e7\u00e3o comprobat\u00f3ria da conclus\u00e3o dos cursos realizados. Durante esse processo, o servidor deve seguir alguns requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>O certificado apresentado e validado para a progress\u00e3o por eleva\u00e7\u00e3o do n\u00edvel de qualifica\u00e7\u00e3o ou titula\u00e7\u00e3o profissional n\u00e3o poder\u00e1 ser reapresentado para qualquer outro processo de desenvolvimento na carreira, sob pena de nulidade do ato, salvo se o servidor tiver direito a ocupar 2 (dois) cargos p\u00fablicos.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>A progress\u00e3o por titula\u00e7\u00e3o deve ser efetivada observando-se a correspond\u00eancia exata entre o t\u00edtulo apresentado e o especificado na matriz de n\u00edvel correspondente.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>A progress\u00e3o por eleva\u00e7\u00e3o de n\u00edvel de qualifica\u00e7\u00e3o profissional deve ser efetivada observado o somat\u00f3rio da carga hor\u00e1ria, apresentada pelo servidor, referente a cursos de qualifica\u00e7\u00e3o profissional, e o especificado na matriz de n\u00edvel correspondente.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Caso o servidor apresente documenta\u00e7\u00e3o de cursos de qualifica\u00e7\u00e3o e\/ou t\u00edtulo que n\u00e3o permita a progress\u00e3o para a matriz desejada, o mesmo poder\u00e1 ser progredido para matriz inferior, desde que cumpra os requisitos da matriz a ser progredido.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>Nos casos de progress\u00e3o por qualifica\u00e7\u00e3o, o servidor, a qualquer tempo, poder\u00e1 apresentar novos certificados ou diplomas com a finalidade de complementar a carga hor\u00e1ria necess\u00e1ria \u00e0 progress\u00e3o para a pr\u00f3xima matriz estabelecida na legisla\u00e7\u00e3o espec\u00edfica do cargo.<\/li>\n<\/ul>\n<p class=\"texto\" style=\"text-align: justify;\"><strong>Responsabilidade da progress\u00e3o<\/strong><\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Segundo a legisla\u00e7\u00e3o, caber\u00e1 aos \u00f3rg\u00e3os e entidades de origem definir as \u00e1reas de conhecimento relacionadas \u00e0s atribui\u00e7\u00f5es do cargo efetivo, bem como \u00e0s \u00e1reas de compet\u00eancia dos \u00f3rg\u00e3os e entidades, nas quais os servidores dever\u00e3o apresentar seus certificados ou diplomas para a progress\u00e3o por eleva\u00e7\u00e3o de n\u00edvel de qualifica\u00e7\u00e3o ou titula\u00e7\u00e3o profissional.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">As \u00e1reas dever\u00e3o ser validadas pela Secretaria de Administra\u00e7\u00e3o e publicadas por meio de Portaria Conjunta da Secretaria de Administra\u00e7\u00e3o com cada \u00f3rg\u00e3o ou entidade.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Al\u00e9m disso, ser\u00e1 de compet\u00eancia do setor de Gest\u00e3o de Pessoas do \u00f3rg\u00e3o ou entidade de origem do servidor verificar a origem da documenta\u00e7\u00e3o e orientar o servidor durante todo o processo de progress\u00e3o.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Com rela\u00e7\u00e3o aos efeitos financeiros da progress\u00e3o por eleva\u00e7\u00e3o de n\u00edvel de qualifica\u00e7\u00e3o ou titula\u00e7\u00e3o profissional, eles devem ocorrer no m\u00eas subsequente ao do deferimento por parte da Comiss\u00e3o prevista na Lei Complementar do cargo.<\/p>\n<p class=\"texto\" style=\"text-align: justify;\">Em casos que o deferimento da Comiss\u00e3o n\u00e3o respeitar o prazo estabelecido na legisla\u00e7\u00e3o, os efeitos financeiros devem retroagir ao m\u00eas subsequente ao t\u00e9rmino daquele prazo.<\/p>\n<p>Fonte: <a href=\"https:\/\/www.diariodepernambuco.com.br\/vida-urbana\/2025\/12\/11701925-estado-regulamenta-progressao-por-qualificacao-ou-titulacao-profissional-de-servidores.html\" target=\"_blank\" rel=\"noopener\">Di\u00e1rio de Pernambuco<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Governo de Pernambuco regulamentou, por meio do decreto N\u00ba 59.890, publicado no Di\u00e1rio Oficial desta ter\u00e7a-feira (2), a progress\u00e3o por eleva\u00e7\u00e3o de n\u00edvel de qualifica\u00e7\u00e3o ou titula\u00e7\u00e3o profissional de&hellip;<\/p>\n","protected":false},"author":2,"featured_media":861,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trabalho"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=860"}],"version-history":[{"count":2,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/860\/revisions"}],"predecessor-version":[{"id":885,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/860\/revisions\/885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/861"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}