{"id":887,"date":"2025-12-08T12:00:59","date_gmt":"2025-12-08T15:00:59","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=887"},"modified":"2025-12-08T02:20:12","modified_gmt":"2025-12-08T05:20:12","slug":"governo-reforca-posicionamento-em-torno-do-fim-da-escala-6x1","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/887\/","title":{"rendered":"Governo refor\u00e7a posicionamento em torno do fim da escala 6&#215;1"},"content":{"rendered":"<p><strong>Ministros e deputados defendem avan\u00e7o da constru\u00e7\u00e3o de um modelo de jornada que garanta vida al\u00e9m do trabalho, com mais sa\u00fade e tempo para lazer e cuidar da fam\u00edlia.<\/strong><\/p>\n<div id=\"content-core\">\n<div id=\"parent-fieldname-text\" class=\"\">\n<div>\n<p>O Governo do Brasil reafirmou seu compromisso em defesa do fim da jornada de trabalho 6&#215;1 sem redu\u00e7\u00e3o de sal\u00e1rio. A defini\u00e7\u00e3o \u00e9 a de que n\u00e3o adianta apenas reduzir a jornada, \u00e9 necess\u00e1rio tamb\u00e9m que os trabalhadores tenham tempo e condi\u00e7\u00e3o de resolver os seus problemas, aproveitar momentos de lazer e cuidar de suas fam\u00edlias.<\/p>\n<p>Foi nesse sentido que a ministra da Secretaria de Rela\u00e7\u00f5es Institucionais da Presid\u00eancia da Rep\u00fablica, Gleisi Hoffmann, concedeu entrevista coletiva, nesta ter\u00e7a-feira, 2 de dezembro, no Pal\u00e1cio do Planalto, ao lado do ministro da Secretaria-Geral da Presid\u00eancia, Guilherme Boulos, ap\u00f3s Reuni\u00e3o de Coordena\u00e7\u00e3o sobre o fim da Escala 6&#215;1.<\/p>\n<p>De acordo com a ministra, essa \u00e9 uma bandeira muito importante do governo do presidente Lula. \u201cDepois da isen\u00e7\u00e3o de pagamento do Imposto de Renda para quem recebe sal\u00e1rio at\u00e9 R$ 5 mil, o fim da escala 6&#215;1 ajuda a garantir qualidade de vida \u00e0 maioria dos trabalhadores e trabalhadoras do Brasil\u201d, disse Gleisi.<\/p>\n<p><strong>SUBCOMISS\u00c3O \u2014<\/strong> A afirma\u00e7\u00e3o da ministra veio ap\u00f3s a apresenta\u00e7\u00e3o do parecer do deputado federal Luiz Gast\u00e3o, relator da Subcomiss\u00e3o da Escala 6&#215;1, que reduz a jornada de trabalho para 40 horas semanais, mas mant\u00e9m a escala 6&#215;1. \u201cN\u00f3s fomos surpreendidos pelo relat\u00f3rio da subcomiss\u00e3o. Ent\u00e3o, vamos seguir defendendo essa posi\u00e7\u00e3o do fim da escala de trabalho 6 x 1, sem redu\u00e7\u00e3o do sal\u00e1rio, no parlamento, na sociedade, nas ruas, e dialogar com o conjunto dos parlamentares. \u00c9 uma pauta aprovada por mais de 70% da popula\u00e7\u00e3o brasileira em todas as pesquisas\u201d, disse o ministro da Secretaria-Geral da Presid\u00eancia, Guilherme Boulos.<\/p>\n<p><strong>ESCALA 6X1 \u2014<\/strong> A PEC 8\/25 prop\u00f5e jornada de quatro dias de trabalho e tr\u00eas de descanso, estabelecendo limite de 36 horas semanais, e extingue a escala 6&#215;1. O debate busca avaliar os impactos da atual escala na sa\u00fade, na qualidade de vida e nas rela\u00e7\u00f5es sociais dos trabalhadores.<\/p>\n<p>A subcomiss\u00e3o especial da escala de trabalho 6&#215;1 da C\u00e2mara dos Deputados ir\u00e1 se reunir nesta quarta-feira, 3 de dezembro, \u00e0s 9h, para discuss\u00e3o e vota\u00e7\u00e3o de propostas legislativas. A proposta ainda ser\u00e1 analisada pela Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a da Casa.<\/p>\n<p class=\"callout\"><strong>PARLAMENTARES \u2014<\/strong> O deputado federal Reginaldo Lopes, autor da primeira PEC (221\/2019) acerca da pauta na C\u00e2mara dos Deputados, e a deputada Daiana Santos, autora do projeto de lei 67\/2025, que prop\u00f5e a redu\u00e7\u00e3o da jornada de trabalho de 44 horas semanais para 40 horas, tamb\u00e9m participaram da coletiva. \u201cO Governo do Brasil unifica sua posi\u00e7\u00e3o e defende o direito ao descanso do povo trabalhador brasileiro. Isso \u00e9 um ganho hist\u00f3rico, \u00e9 o fim da escravid\u00e3o moderna\u201d, ressaltou Reginaldo Lopes. \u201cEu acho que a sociedade brasileira j\u00e1 est\u00e1 amadurecida para esse momento\u201d, complementou Daiana Santos.<\/p>\n<p>Fonte: <a href=\"https:\/\/www.gov.br\/secom\/pt-br\/assuntos\/noticias\/2025\/12\/governo-reforca-posicionamento-em-torno-do-fim-da-escala-6x1\" target=\"_blank\" rel=\"noopener\">gov.br<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ministros e deputados defendem avan\u00e7o da constru\u00e7\u00e3o de um modelo de jornada que garanta vida al\u00e9m do trabalho, com mais sa\u00fade e tempo para lazer e cuidar da fam\u00edlia. O&hellip;<\/p>\n","protected":false},"author":2,"featured_media":888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trabalho"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=887"}],"version-history":[{"count":1,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/887\/revisions"}],"predecessor-version":[{"id":889,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/887\/revisions\/889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/888"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}