{"id":968,"date":"2025-12-26T08:00:38","date_gmt":"2025-12-26T11:00:38","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=968"},"modified":"2025-12-25T00:31:32","modified_gmt":"2025-12-25T03:31:32","slug":"governo-lanca-programa-para-ampliar-o-registro-civil-de-nascimentos","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/968\/","title":{"rendered":"Governo lan\u00e7a programa para ampliar o registro civil de nascimentos."},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>O Programa re\u00fane a\u00e7\u00f5es de promo\u00e7\u00e3o da cidadania e de defesa dos direitos humanos voltadas \u00e0 erradica\u00e7\u00e3o do sub-registro civil de nascimento no Brasil<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">O Governo do Brasil oficializou, nesta ter\u00e7a-feira (23), o Programa Ra\u00edzes da Cidadania. A iniciativa tem como objetivo ampliar e qualificar o registro civil de nascimento nos estabelecimentos de sa\u00fade que realizam partos em todo o pa\u00eds, fortalecendo o acesso \u00e0 documenta\u00e7\u00e3o b\u00e1sica como um direito fundamental.<\/p>\n<p style=\"text-align: justify;\">A Portaria Conjunta n\u00ba 7, que institui o programa, foi assinada pela ministra dos Direitos Humanos e da Cidadania, Maca\u00e9 Evaristo, e pelo ministro da Sa\u00fade, Alexandre Padilha, e publicada no Di\u00e1rio Oficial da Uni\u00e3o.<\/p>\n<p style=\"text-align: justify;\">O Programa re\u00fane a\u00e7\u00f5es de promo\u00e7\u00e3o da cidadania e de defesa dos direitos humanos voltadas \u00e0 erradica\u00e7\u00e3o do sub-registro civil de nascimento no Brasil. A estrat\u00e9gia envolve coopera\u00e7\u00e3o t\u00e9cnica, articula\u00e7\u00e3o interinstitucional e implementa\u00e7\u00e3o de mecanismos de integra\u00e7\u00e3o entre sistemas existentes.<\/p>\n<p style=\"text-align: justify;\">A portaria lista os cinco objetivos da iniciativa:<\/p>\n<p style=\"text-align: justify;\">\u00bb reduzir os \u00edndices de sub-registro civil de nascimento;<br \/>\n\u00bb fortalecer a pol\u00edtica de unidades interligadas como estrat\u00e9gia nacional permanente;<br \/>\n\u00bb aumentar progressivamente a quantidade de estabelecimentos de sa\u00fade com estrutura para lavratura de registro de nascimento;<br \/>\n\u00bb elevar o \u00edndice de cobertura do registro civil de nascimento nos estabelecimentos de sa\u00fade; e<br \/>\n\u00bb executar campanhas educativas e capacita\u00e7\u00f5es continuadas, em articula\u00e7\u00e3o com \u00f3rg\u00e3os parceiros, voltadas \u00e0 valoriza\u00e7\u00e3o do registro civil como ato de cidadania.<\/p>\n<p style=\"text-align: justify;\">O Programa Ra\u00edzes da Cidadania \u00e9 orientado por princ\u00edpios como a dignidade da pessoa humana; a universaliza\u00e7\u00e3o do direito \u00e0 identidade civil e \u00e0 documenta\u00e7\u00e3o b\u00e1sica; a gratuidade e equidade no acesso ao registro civil de nascimento; a integralidade e intersetorialidade na execu\u00e7\u00e3o das a\u00e7\u00f5es; e a efici\u00eancia e transpar\u00eancia administrativa.<\/p>\n<p style=\"text-align: justify;\">Entre os eixos estrat\u00e9gicos do programa est\u00e3o o mapeamento e an\u00e1lise dos dados, com levantamento e organiza\u00e7\u00e3o de informa\u00e7\u00f5es que subsidiem a expans\u00e3o de Unidades Interligadas nos estabelecimentos de sa\u00fade que realizam partos, al\u00e9m do aprimoramento da qualidade dos dados dispon\u00edveis.<\/p>\n<p style=\"text-align: justify;\">A iniciativa prev\u00ea articula\u00e7\u00e3o entre Uni\u00e3o, estados, Distrito Federal, munic\u00edpios, Poder Legislativo, sistemas de justi\u00e7a, sociedade civil e Comit\u00eas Gestores Estaduais e Municipais de Erradica\u00e7\u00e3o do Sub-registro Civil de Nascimento e Acesso \u00e0 Documenta\u00e7\u00e3o B\u00e1sica. As a\u00e7\u00f5es incluem a implanta\u00e7\u00e3o de Unidades Interligadas em maternidades localizadas nos munic\u00edpios com maiores \u00edndices de sub-registro, bem como a capacita\u00e7\u00e3o de profissionais de sa\u00fade e registradores civis e a produ\u00e7\u00e3o de materiais informativos.<\/p>\n<p style=\"text-align: justify;\">O Minist\u00e9rio da Sa\u00fade ser\u00e1 respons\u00e1vel por disponibilizar e qualificar os dados do Sistema de Informa\u00e7\u00f5es sobre Nascidos Vivos (Sinasc), al\u00e9m de desenvolver indicadores e metodologias de monitoramento. J\u00e1 o Minist\u00e9rio dos Direitos Humanos e da Cidadania apoiar\u00e1 o Minist\u00e9rio da Sa\u00fade, o Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) e o Comit\u00ea Gestor do Sistema Nacional de Informa\u00e7\u00f5es de Registro Civil (CGSirc) na produ\u00e7\u00e3o, organiza\u00e7\u00e3o e cruzamento de informa\u00e7\u00f5es necess\u00e1rias \u00e0 amplia\u00e7\u00e3o e ao aprimoramento das Unidades Interligadas.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m disso, a pasta prestar\u00e1 apoio t\u00e9cnico aos estados e capitais na cria\u00e7\u00e3o de Comit\u00eas Gestores Estaduais e Municipais de Erradica\u00e7\u00e3o do Sub-registro Civil de Nascimento e de Documenta\u00e7\u00e3o B\u00e1sica, al\u00e9m de colaborar na elabora\u00e7\u00e3o de documentos t\u00e9cnicos que orientem o funcionamento das Unidades Interligadas e estabele\u00e7am fluxos nacionais, respeitadas as especificidades regionais. O Minist\u00e9rio dos Direitos Humanos e da Cidadania ainda realizar\u00e1 curso sobre o tema, que ser\u00e1 ofertado pela Escola Nacional de Administra\u00e7\u00e3o P\u00fablica (Enap).<\/p>\n<p>Fonte: <a href=\"https:\/\/www.novonoticias.com.br\/governo-lanca-programa-para-ampliar-o-registro-civil-de-nascimentos-veja-como-funciona\/\" target=\"_blank\" rel=\"noopener\">Novo Not\u00edcias<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Programa re\u00fane a\u00e7\u00f5es de promo\u00e7\u00e3o da cidadania e de defesa dos direitos humanos voltadas \u00e0 erradica\u00e7\u00e3o do sub-registro civil de nascimento no Brasil O Governo do Brasil oficializou, nesta&hellip;<\/p>\n","protected":false},"author":2,"featured_media":492,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[61],"tags":[],"class_list":["post-968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidadania"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=968"}],"version-history":[{"count":1,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/968\/revisions"}],"predecessor-version":[{"id":969,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/968\/revisions\/969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/492"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}