{"id":970,"date":"2025-12-27T18:00:35","date_gmt":"2025-12-27T21:00:35","guid":{"rendered":"https:\/\/puxandoassunto.com.br\/site\/?p=970"},"modified":"2025-12-26T16:00:31","modified_gmt":"2025-12-26T19:00:31","slug":"ufrn-perdera-r-147-milhoes-em-2026-com-o-corte-de-orcamento-para-universidades","status":"publish","type":"post","link":"https:\/\/puxandoassunto.com.br\/site\/970\/","title":{"rendered":"UFRN perder\u00e1 R$ 14,7 milh\u00f5es em 2026 com o corte de or\u00e7amento para universidades"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>O reitor Jos\u00e9 Daniel Diniz Melo manifestou preocupa\u00e7\u00e3o em nota divulgada nesta quarta-feira (24); or\u00e7amento ser\u00e1 menor que o de 2025<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">A Reitoria da Universidade Federal do Rio Grande do Norte (UFRN) emitiu um alerta sobre a redu\u00e7\u00e3o or\u00e7ament\u00e1ria imposta \u00e0s universidades federais pelo Congresso Nacional durante a tramita\u00e7\u00e3o da Lei Or\u00e7ament\u00e1ria Anual (LOA) de 2026. Na UFRN, o corte chega a 7,18%, o que representa uma perda de R$ 14.738.445,00 em rela\u00e7\u00e3o ao que estava previsto no projeto original.<\/p>\n<p style=\"text-align: justify;\">Com a aprova\u00e7\u00e3o, o or\u00e7amento de custeio da institui\u00e7\u00e3o para o pr\u00f3ximo ano caiu de R$ 205,1 milh\u00f5es para R$ 190,4 milh\u00f5es. O montante aprovado para 2026 consegue ser, inclusive, inferior ao or\u00e7amento discricion\u00e1rio de 2025, que foi de R$ 195,6 milh\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Segundo o reitor da UFRN, Jos\u00e9 Daniel Diniz Melo, a tesourada nos recursos compromete diretamente a manuten\u00e7\u00e3o b\u00e1sica da universidade. \u201cEsses cortes impactam fortemente o funcionamento da Universidade, em compromissos como pagamentos de energia el\u00e9trica, contratos de terceiriza\u00e7\u00e3o e na assist\u00eancia estudantil\u201d, destacou o gestor.<\/p>\n<p style=\"text-align: justify;\">A maior preocupa\u00e7\u00e3o recai sobre a assist\u00eancia estudantil. O setor, que j\u00e1 havia demandado complementa\u00e7\u00e3o de recursos em 2025 por ser insuficiente, sofreu um corte de 7,33% para 2026 em compara\u00e7\u00e3o ao projeto inicial, ficando com verba menor que a do ano corrente.<\/p>\n<p style=\"text-align: justify;\">Diante do cen\u00e1rio, o reitor Daniel Diniz disse esperar que o Minist\u00e9rio da Educa\u00e7\u00e3o (MEC) atue para recompor os valores, repetindo o que foi feito em anos anteriores. Para o gestor, as institui\u00e7\u00f5es federais precisam de um modelo de financiamento que garanta previsibilidade e recursos suficientes para o cumprimento de suas miss\u00f5es.<\/p>\n<p style=\"text-align: justify;\"><strong>Cen\u00e1rio Nacional<\/strong><br \/>\nA crise financeira n\u00e3o \u00e9 exclusiva do Rio Grande do Norte. De acordo com an\u00e1lise da Associa\u00e7\u00e3o Nacional dos Dirigentes das Institui\u00e7\u00f5es Federais de Ensino Superior (Andifes), o or\u00e7amento das 69 universidades federais do pa\u00eds sofreu um corte total de R$ 488 milh\u00f5es. A redu\u00e7\u00e3o m\u00e9dia nacional \u00e9 de 7,05% nos recursos discricion\u00e1rios.<\/p>\n<p style=\"text-align: justify;\">Para a Andifes, \u201cos cortes aprovados agravam um quadro j\u00e1 cr\u00edtico\u201d do ensino superior brasileiro.<\/p>\n<p>Fonte: <a href=\"https:\/\/www.novonoticias.com.br\/ufrn-perdera-r-147-milhoes-em-2026-com-o-corte-de-orcamento-para-universidades\/\" target=\"_blank\" rel=\"noopener\">Novo Not\u00edcias<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O reitor Jos\u00e9 Daniel Diniz Melo manifestou preocupa\u00e7\u00e3o em nota divulgada nesta quarta-feira (24); or\u00e7amento ser\u00e1 menor que o de 2025 A Reitoria da Universidade Federal do Rio Grande do&hellip;<\/p>\n","protected":false},"author":2,"featured_media":972,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao"],"_links":{"self":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/comments?post=970"}],"version-history":[{"count":1,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/970\/revisions"}],"predecessor-version":[{"id":971,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/posts\/970\/revisions\/971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media\/972"}],"wp:attachment":[{"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/media?parent=970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/categories?post=970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puxandoassunto.com.br\/site\/wp-json\/wp\/v2\/tags?post=970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}